{"id":9575,"date":"2025-09-18T15:09:21","date_gmt":"2025-09-18T21:09:21","guid":{"rendered":"https:\/\/denjustpeace.org\/?p=9575"},"modified":"2025-09-19T15:02:36","modified_gmt":"2025-09-19T21:02:36","slug":"9575","status":"publish","type":"post","link":"https:\/\/denjustpeace.org\/es\/2025\/09\/9575\/","title":{"rendered":"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025."},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"https:\/\/denjustpeace.org\/en\/wp-json\/wp\/v2\/posts\/9575\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"English\">English<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en English.<\/p>\n","protected":false},"author":36,"featured_media":9576,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[10,25,196],"tags":[],"class_list":["post-9575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-events","category-featured","category-fundraising"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025. - Denver Justice &amp; Peace Committee<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/denjustpeace.org\/2025\/09\/9575\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025. - Denver Justice &amp; Peace Committee\" \/>\n<meta property=\"og:description\" content=\"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en English.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/denjustpeace.org\/2025\/09\/9575\/\" \/>\n<meta property=\"og:site_name\" content=\"Denver Justice &amp; Peace Committee\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DenverJusticeandPeaceCommittee\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T21:09:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-19T21:02:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1429\" \/>\n\t<meta property=\"og:image:height\" content=\"2000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Rebeca Zuniga-Hamlin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@denjustpeace\" \/>\n<meta name=\"twitter:site\" content=\"@denjustpeace\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Rebeca Zuniga-Hamlin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/\"},\"author\":{\"name\":\"Rebeca Zuniga-Hamlin\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#\\\/schema\\\/person\\\/229dccb0d0445b8783666da08f3c0caa\"},\"headline\":\"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025.\",\"datePublished\":\"2025-09-18T21:09:21+00:00\",\"dateModified\":\"2025-09-19T21:02:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/\"},\"wordCount\":125,\"publisher\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/denjustpeace.org\\\/wordpress\\\/wp-content\\\/uploads\\\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg\",\"articleSection\":[\"Eventos\",\"Destacado\",\"Fundraising\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/\",\"url\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/\",\"name\":\"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025. - Denver Justice &amp; Peace Committee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/denjustpeace.org\\\/wordpress\\\/wp-content\\\/uploads\\\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg\",\"datePublished\":\"2025-09-18T21:09:21+00:00\",\"dateModified\":\"2025-09-19T21:02:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/#primaryimage\",\"url\":\"https:\\\/\\\/denjustpeace.org\\\/wordpress\\\/wp-content\\\/uploads\\\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg\",\"contentUrl\":\"https:\\\/\\\/denjustpeace.org\\\/wordpress\\\/wp-content\\\/uploads\\\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg\",\"width\":1429,\"height\":2000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/2025\\\/09\\\/9575\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/denjustpeace.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reserve la Fecha: Noche de Premios, 7 de noviembre 2025.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#website\",\"url\":\"https:\\\/\\\/denjustpeace.org\\\/\",\"name\":\"Denver Justice &amp; Peace Committee\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/denjustpeace.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#organization\",\"name\":\"Denver Justice & Peace Committee\",\"url\":\"https:\\\/\\\/denjustpeace.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/denjustpeace.org\\\/wordpress\\\/wp-content\\\/uploads\\\/djpclogo.jpg\",\"contentUrl\":\"http:\\\/\\\/denjustpeace.org\\\/wordpress\\\/wp-content\\\/uploads\\\/djpclogo.jpg\",\"width\":260,\"height\":260,\"caption\":\"Denver Justice & Peace Committee\"},\"image\":{\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DenverJusticeandPeaceCommittee\\\/\",\"https:\\\/\\\/x.com\\\/denjustpeace\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/denjustpeace.org\\\/#\\\/schema\\\/person\\\/229dccb0d0445b8783666da08f3c0caa\",\"name\":\"Rebeca Zuniga-Hamlin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025. - Denver Justice &amp; Peace Committee","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/denjustpeace.org\/2025\/09\/9575\/","og_locale":"es_ES","og_type":"article","og_title":"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025. - Denver Justice &amp; Peace Committee","og_description":"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en English.","og_url":"https:\/\/denjustpeace.org\/2025\/09\/9575\/","og_site_name":"Denver Justice &amp; Peace Committee","article_publisher":"https:\/\/www.facebook.com\/DenverJusticeandPeaceCommittee\/","article_published_time":"2025-09-18T21:09:21+00:00","article_modified_time":"2025-09-19T21:02:36+00:00","og_image":[{"width":1429,"height":2000,"url":"https:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg","type":"image\/jpeg"}],"author":"Rebeca Zuniga-Hamlin","twitter_card":"summary_large_image","twitter_creator":"@denjustpeace","twitter_site":"@denjustpeace","twitter_misc":{"Escrito por":"Rebeca Zuniga-Hamlin","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/#article","isPartOf":{"@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/"},"author":{"name":"Rebeca Zuniga-Hamlin","@id":"https:\/\/denjustpeace.org\/#\/schema\/person\/229dccb0d0445b8783666da08f3c0caa"},"headline":"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025.","datePublished":"2025-09-18T21:09:21+00:00","dateModified":"2025-09-19T21:02:36+00:00","mainEntityOfPage":{"@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/"},"wordCount":125,"publisher":{"@id":"https:\/\/denjustpeace.org\/#organization"},"image":{"@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/#primaryimage"},"thumbnailUrl":"https:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg","articleSection":["Eventos","Destacado","Fundraising"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/","url":"https:\/\/denjustpeace.org\/2025\/09\/9575\/","name":"(English) Reserve la Fecha: Noche de Premios, 7 de noviembre 2025. - Denver Justice &amp; Peace Committee","isPartOf":{"@id":"https:\/\/denjustpeace.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/#primaryimage"},"image":{"@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/#primaryimage"},"thumbnailUrl":"https:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg","datePublished":"2025-09-18T21:09:21+00:00","dateModified":"2025-09-19T21:02:36+00:00","breadcrumb":{"@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/denjustpeace.org\/2025\/09\/9575\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/#primaryimage","url":"https:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg","contentUrl":"https:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/Noche-de-Premios-2025-Guarde-la-Fecha.jpg","width":1429,"height":2000},{"@type":"BreadcrumbList","@id":"https:\/\/denjustpeace.org\/2025\/09\/9575\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/denjustpeace.org\/"},{"@type":"ListItem","position":2,"name":"Reserve la Fecha: Noche de Premios, 7 de noviembre 2025."}]},{"@type":"WebSite","@id":"https:\/\/denjustpeace.org\/#website","url":"https:\/\/denjustpeace.org\/","name":"Denver Justice &amp; Peace Committee","description":"","publisher":{"@id":"https:\/\/denjustpeace.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/denjustpeace.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/denjustpeace.org\/#organization","name":"Denver Justice & Peace Committee","url":"https:\/\/denjustpeace.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/denjustpeace.org\/#\/schema\/logo\/image\/","url":"http:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/djpclogo.jpg","contentUrl":"http:\/\/denjustpeace.org\/wordpress\/wp-content\/uploads\/djpclogo.jpg","width":260,"height":260,"caption":"Denver Justice & Peace Committee"},"image":{"@id":"https:\/\/denjustpeace.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DenverJusticeandPeaceCommittee\/","https:\/\/x.com\/denjustpeace"]},{"@type":"Person","@id":"https:\/\/denjustpeace.org\/#\/schema\/person\/229dccb0d0445b8783666da08f3c0caa","name":"Rebeca Zuniga-Hamlin"}]}},"_links":{"self":[{"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/posts\/9575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/comments?post=9575"}],"version-history":[{"count":4,"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/posts\/9575\/revisions"}],"predecessor-version":[{"id":9588,"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/posts\/9575\/revisions\/9588"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/media\/9576"}],"wp:attachment":[{"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/media?parent=9575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/categories?post=9575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/denjustpeace.org\/es\/wp-json\/wp\/v2\/tags?post=9575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}